{"id":3302,"date":"2021-04-22T18:32:44","date_gmt":"2021-04-22T18:32:44","guid":{"rendered":"https:\/\/berdemozes.ro\/?p=3302"},"modified":"2021-04-27T12:12:44","modified_gmt":"2021-04-27T12:12:44","slug":"kolteszet-napi-unneples-az-online-terben-2021","status":"publish","type":"post","link":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/","title":{"rendered":"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021"},"content":{"rendered":"<p><\/p>\n\n\n<p>A Sz\u00e9kelykereszt\u00fari V\u00e1rosi K\u00f6nyvt\u00e1r j\u00f3volt\u00e1b\u00f3l az idei k\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rbe k\u00f6lt\u00f6z\u00f6tt. K\u00fcl\u00f6nb\u00f6z\u0151 korcsoportokban versenyezhettek a v\u00e1ros lak\u00f3i egy \u00e1ltaluk v\u00e1lasztott verssel. Iskol\u00e1nk di\u00e1kjai is al\u00e1vetett\u00e9k magukat a pr\u00f3b\u00e1nak, \u00e9s sz\u00e9p eredm\u00e9nyeket \u00e9rtek el.<\/p>\n\n\n\n<p>L\u00e9vai Attila a 9-12. oszt\u00e1lyosok kateg\u00f3ri\u00e1j\u00e1ban k\u00fcl\u00f6nd\u00edjas, m\u00edg Atanackovic Natalija els\u0151 helyezett lett. Szavalat\u00e1t maga az \u00edr\u00f3, Lackfi J\u00e1nos is elismerte, \u00e9s megosztotta saj\u00e1t Facebook oldal\u00e1n. Gratul\u00e1lunk!<\/p>\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/172715513_5363695503701868_7235763778715745804_n-678x1024.jpg\" alt=\"\" class=\"wp-image-3303\" width=\"268\" height=\"403\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"http:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/48F18500B3C042CCB4FD8628966F62BC.jpg\" alt=\"\" class=\"wp-image-3312\" width=\"260\" height=\"348\" srcset=\"https:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/48F18500B3C042CCB4FD8628966F62BC.jpg 645w, https:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/48F18500B3C042CCB4FD8628966F62BC-224x300.jpg 224w, https:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/48F18500B3C042CCB4FD8628966F62BC-300x400.jpg 300w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/figure><\/div>\n\n\n\n<\/p>\n<p>\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>A Sz\u00e9kelykereszt\u00fari V\u00e1rosi K\u00f6nyvt\u00e1r j\u00f3volt\u00e1b\u00f3l az idei k\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rbe k\u00f6lt\u00f6z\u00f6tt. K\u00fcl\u00f6nb\u00f6z\u0151 korcsoportokban versenyezhettek a v\u00e1ros lak\u00f3i egy \u00e1ltaluk v\u00e1lasztott verssel. Iskol\u00e1nk di\u00e1kjai is al\u00e1vetett\u00e9k magukat a pr\u00f3b\u00e1nak, &#8230;<\/p>\n","protected":false},"author":4,"featured_media":3303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021 - Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021 - Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium\" \/>\n<meta property=\"og:description\" content=\"A Sz\u00e9kelykereszt\u00fari V\u00e1rosi K\u00f6nyvt\u00e1r j\u00f3volt\u00e1b\u00f3l az idei k\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rbe k\u00f6lt\u00f6z\u00f6tt. K\u00fcl\u00f6nb\u00f6z\u0151 korcsoportokban versenyezhettek a v\u00e1ros lak\u00f3i egy \u00e1ltaluk v\u00e1lasztott verssel. Iskol\u00e1nk di\u00e1kjai is al\u00e1vetett\u00e9k magukat a pr\u00f3b\u00e1nak, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bmugim\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-22T18:32:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T12:12:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/172715513_5363695503701868_7235763778715745804_n-e1619116476919.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1224\" \/>\n\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Farkas Orsolya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Farkas Orsolya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/\"},\"author\":{\"name\":\"Farkas Orsolya\",\"@id\":\"https:\/\/berdemozes.ro\/#\/schema\/person\/8bbbc3b75a99444fc656441a12a5ccc5\"},\"headline\":\"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021\",\"datePublished\":\"2021-04-22T18:32:44+00:00\",\"dateModified\":\"2021-04-27T12:12:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/\"},\"wordCount\":114,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/berdemozes.ro\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/\",\"url\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/\",\"name\":\"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021 - Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium\",\"isPartOf\":{\"@id\":\"https:\/\/berdemozes.ro\/#website\"},\"datePublished\":\"2021-04-22T18:32:44+00:00\",\"dateModified\":\"2021-04-27T12:12:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/berdemozes.ro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/berdemozes.ro\/#website\",\"url\":\"https:\/\/berdemozes.ro\/\",\"name\":\"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium\",\"description\":\"A sz\u00e9kelykereszt\u00fari Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium weboldala.\",\"publisher\":{\"@id\":\"https:\/\/berdemozes.ro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/berdemozes.ro\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/berdemozes.ro\/#organization\",\"name\":\"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium\",\"url\":\"https:\/\/berdemozes.ro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/berdemozes.ro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/berdemozes.ro\/wp-content\/uploads\/2020\/11\/cropped-HEADER-LOGO-2-1.png\",\"contentUrl\":\"https:\/\/berdemozes.ro\/wp-content\/uploads\/2020\/11\/cropped-HEADER-LOGO-2-1.png\",\"width\":213,\"height\":48,\"caption\":\"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium\"},\"image\":{\"@id\":\"https:\/\/berdemozes.ro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bmugim\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/berdemozes.ro\/#\/schema\/person\/8bbbc3b75a99444fc656441a12a5ccc5\",\"name\":\"Farkas Orsolya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/berdemozes.ro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a37b7582dc17c5d13da45451dfb3476e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a37b7582dc17c5d13da45451dfb3476e?s=96&d=mm&r=g\",\"caption\":\"Farkas Orsolya\"},\"url\":\"https:\/\/berdemozes.ro\/index.php\/author\/farkas-orsolya\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021 - Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"hu_HU","og_type":"article","og_title":"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021 - Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium","og_description":"A Sz\u00e9kelykereszt\u00fari V\u00e1rosi K\u00f6nyvt\u00e1r j\u00f3volt\u00e1b\u00f3l az idei k\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rbe k\u00f6lt\u00f6z\u00f6tt. K\u00fcl\u00f6nb\u00f6z\u0151 korcsoportokban versenyezhettek a v\u00e1ros lak\u00f3i egy \u00e1ltaluk v\u00e1lasztott verssel. Iskol\u00e1nk di\u00e1kjai is al\u00e1vetett\u00e9k magukat a pr\u00f3b\u00e1nak, ...","og_url":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/","og_site_name":"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium","article_publisher":"https:\/\/www.facebook.com\/bmugim","article_published_time":"2021-04-22T18:32:44+00:00","article_modified_time":"2021-04-27T12:12:44+00:00","og_image":[{"width":1224,"height":813,"url":"https:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/172715513_5363695503701868_7235763778715745804_n-e1619116476919.jpg","type":"image\/jpeg"}],"author":"Farkas Orsolya","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"Farkas Orsolya","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#article","isPartOf":{"@id":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/"},"author":{"name":"Farkas Orsolya","@id":"https:\/\/berdemozes.ro\/#\/schema\/person\/8bbbc3b75a99444fc656441a12a5ccc5"},"headline":"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021","datePublished":"2021-04-22T18:32:44+00:00","dateModified":"2021-04-27T12:12:44+00:00","mainEntityOfPage":{"@id":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/"},"wordCount":114,"commentCount":0,"publisher":{"@id":"https:\/\/berdemozes.ro\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"hu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/","url":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/","name":"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021 - Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium","isPartOf":{"@id":"https:\/\/berdemozes.ro\/#website"},"datePublished":"2021-04-22T18:32:44+00:00","dateModified":"2021-04-27T12:12:44+00:00","breadcrumb":{"@id":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/berdemozes.ro\/index.php\/2021\/04\/22\/kolteszet-napi-unneples-az-online-terben-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berdemozes.ro\/"},{"@type":"ListItem","position":2,"name":"K\u00f6lt\u00e9szetnapi \u00fcnnepl\u00e9s az online t\u00e9rben \u2013 2021"}]},{"@type":"WebSite","@id":"https:\/\/berdemozes.ro\/#website","url":"https:\/\/berdemozes.ro\/","name":"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium","description":"A sz\u00e9kelykereszt\u00fari Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium weboldala.","publisher":{"@id":"https:\/\/berdemozes.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berdemozes.ro\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/berdemozes.ro\/#organization","name":"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium","url":"https:\/\/berdemozes.ro\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/berdemozes.ro\/#\/schema\/logo\/image\/","url":"https:\/\/berdemozes.ro\/wp-content\/uploads\/2020\/11\/cropped-HEADER-LOGO-2-1.png","contentUrl":"https:\/\/berdemozes.ro\/wp-content\/uploads\/2020\/11\/cropped-HEADER-LOGO-2-1.png","width":213,"height":48,"caption":"Berde M\u00f3zes Unit\u00e1rius Gimn\u00e1zium"},"image":{"@id":"https:\/\/berdemozes.ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bmugim"]},{"@type":"Person","@id":"https:\/\/berdemozes.ro\/#\/schema\/person\/8bbbc3b75a99444fc656441a12a5ccc5","name":"Farkas Orsolya","image":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/berdemozes.ro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a37b7582dc17c5d13da45451dfb3476e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a37b7582dc17c5d13da45451dfb3476e?s=96&d=mm&r=g","caption":"Farkas Orsolya"},"url":"https:\/\/berdemozes.ro\/index.php\/author\/farkas-orsolya\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/berdemozes.ro\/wp-content\/uploads\/2021\/04\/172715513_5363695503701868_7235763778715745804_n-e1619116476919.jpg","_links":{"self":[{"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/posts\/3302"}],"collection":[{"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/comments?post=3302"}],"version-history":[{"count":9,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/posts\/3302\/revisions"}],"predecessor-version":[{"id":3324,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/posts\/3302\/revisions\/3324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/media\/3303"}],"wp:attachment":[{"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/media?parent=3302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/categories?post=3302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berdemozes.ro\/index.php\/wp-json\/wp\/v2\/tags?post=3302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}